{"id":15744,"date":"2012-09-05T21:11:13","date_gmt":"2012-09-05T20:11:13","guid":{"rendered":"http:\/\/www.burks.de\/burksblog\/?p=15744"},"modified":"2012-09-05T21:14:34","modified_gmt":"2012-09-05T20:14:34","slug":"auf-posten-in-einsamer-nacht","status":"publish","type":"post","link":"https:\/\/www.burks.de\/burksblog\/2012\/09\/05\/auf-posten-in-einsamer-nacht","title":{"rendered":"Auf Posten in einsamer Nacht"},"content":{"rendered":"<div class=\"lyte-wrapper fourthree\" title=\"&amp;quot;Auf Posten&amp;quot;( &amp;quot;Es gehet alles vor&uuml;ber&amp;quot;) &amp;quot;\u041d\u0430 \u043f\u043e\u0441\u0442\u0443&amp;quot;(\u0412\u0441\u0435 \u043f\u0440\u043e\u0445\u043e\u0434\u0438\u0442)\" style=\"width:480px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_uOUf0RiZOzM\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/i.ytimg.com\/vi\/uOUf0RiZOzM\/hqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/uOUf0RiZOzM\" \/><meta itemprop=\"duration\" content=\"PT3M20S\" \/><meta itemprop=\"uploadDate\" content=\"2010-11-24T13:05:43Z\" \/><\/div><div id=\"lyte_uOUf0RiZOzM\" data-src=\"https:\/\/i.ytimg.com\/vi\/uOUf0RiZOzM\/hqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">&quot;Auf Posten&quot;( &quot;Es gehet alles vor\u00fcber&quot;) &quot;\u041d\u0430 \u043f\u043e\u0441\u0442\u0443&quot;(\u0412\u0441\u0435 \u043f\u0440\u043e\u0445\u043e\u0434\u0438\u0442)<\/div><\/div><button tabindex=\"0\" class=\"play\"><\/button><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/uOUf0RiZOzM\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/uOUf0RiZOzM\/0.jpg\" alt=\"&amp;quot;Auf Posten&amp;quot;( &amp;quot;Es gehet alles vor&uuml;ber&amp;quot;) &amp;quot;\u041d\u0430 \u043f\u043e\u0441\u0442\u0443&amp;quot;(\u0412\u0441\u0435 \u043f\u0440\u043e\u0445\u043e\u0434\u0438\u0442)\" width=\"480\" height=\"340\" \/><br \/>Dieses Video auf YouTube ansehen<\/a><\/noscript><meta itemprop=\"description\" content=\"&quot;Es gehet alles vor\u00fcber&quot; &quot;Auf Posten in einsamer Nacht&quot; &quot;&quot;\u041d\u0430 \u043f\u043e\u0441\u0442\u0443 &quot;\u043f\u0435\u0440\u0435\u0432\u043e\u0434 \u041d\u0430\u0442\u0430\u043b\u044c\u0438 \u041a\u0440\u0430\u0443\u0431\u043d\u0435\u0440 Singgruppe &quot;Lorelei&quot; Konzert DRB Sankt-Petersburg. 18.11.2010 Leiterin Natalia Kraubner. \u0425\u0443\u0434\u043e\u0436\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0439 \u0440\u0443\u043a\u043e\u0432\u043e\u0434\u0438\u0442\u0435\u043b\u044c \u0430\u043d\u0441\u0430\u043c\u0431\u043b\u044f &quot;\u041b\u043e\u0440\u0435\u043b\u0435\u044f&quot; - \u041d\u0430\u0442\u0430\u043b\u044c\u044f \u041a\u0440\u0430\u0443\u0431\u043d\u0435\u0440 Read more: http:\/\/kraubner.ragtime.ru\/\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:480px;margin:5px;\"><br\/><span class=\"lyte_disclaimer\">Das Video wird von YouTube eingebettet und erst beim Klick auf den Play-Button geladen. Es gelten die <a href=\"https:\/\/policies.google.com\/privacy?hl=de\">Datenschutzerkl\u00e4rungen von Google<\/A>.<\/span><\/div><\/p>\n<p align=left>Beim <a href=\"http:\/\/www.schockwellenreiter.de\/blog\/2012\/09\/05\/musik-im-netz\/\">Schockwellenreiter<\/a> wurde ich auf das wunderbare <a href=\"http:\/\/www.liederlexikon.de\/\">Historisch-kritische Liederlexikon<\/a> aufmerksam. F\u00fcr Blogger wie mich passt nat\u00fcrlich &#8222;<a href=\"http:\/\/www.liederlexikon.de\/lieder\/es_geht_alles_vorueber\">Auf Posten in einsamer Nacht<\/a>&#8222;. &#8222;Singgruppe Lorelei&#8220; aus St. Petersburg (woher auch sonst), gesucht und gefunden bei Youtube! Lalala tamtam! Ohrwurm!<\/p>\n<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-bottom-right\"><a href=\"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/posts\/15744?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/www.burks.de\/burksblog\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"PDF anzeigen\" \/><\/a><a href=\"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/posts\/15744?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/www.burks.de\/burksblog\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Inhalt drucken\" \/><\/a><\/div><div class=\"twoclick_social_bookmarks_post_15744 social_share_privacy clearfix 1.6.4 locale-de_DE sprite-de_DE\"><\/div><div class=\"twoclick-js\"><script type=\"text\/javascript\">\/* <![CDATA[ *\/\njQuery(document).ready(function($){if($('.twoclick_social_bookmarks_post_15744')){$('.twoclick_social_bookmarks_post_15744').socialSharePrivacy({\"services\":{\"facebook\":{\"status\":\"on\",\"txt_info\":\"2 Klicks f\\u00fcr mehr Datenschutz: Erst wenn Sie hier klicken, wird der Button aktiv und Sie k\\u00f6nnen Ihre Empfehlung an Facebook senden. Schon beim Aktivieren werden Daten an Dritte \\u00fcbertragen - siehe <em>i<\\\/em>.\",\"perma_option\":\"off\",\"action\":\"recommend\",\"language\":\"de_DE\"},\"twitter\":{\"reply_to\":\"\",\"tweet_text\":\"%20Auf%20Posten%20in%20einsamer%20Nacht%20%C2%BB%20Burks%27%20Blog%20-%20in%20dubio%20pro%20contra.%20De%20...\",\"status\":\"on\",\"txt_info\":\"2 Klicks f\\u00fcr mehr Datenschutz: Erst wenn Sie hier klicken, wird der Button aktiv und Sie k\\u00f6nnen Ihre Empfehlung an Twitter senden. Schon beim Aktivieren werden Daten an Dritte \\u00fcbertragen - siehe <em>i<\\\/em>.\",\"perma_option\":\"off\",\"language\":\"de\",\"referrer_track\":\"\"}},\"txt_help\":\"Wenn Sie diese Felder durch einen Klick aktivieren, werden Informationen an Facebook, Twitter, Flattr, Xing, t3n, LinkedIn, Pinterest oder Google eventuell ins Ausland \\u00fcbertragen und unter Umst\\u00e4nden auch dort gespeichert. N\\u00e4heres erfahren Sie durch einen Klick auf das <em>i<\\\/em>.\",\"settings_perma\":\"Dauerhaft aktivieren und Daten\\u00fcber-tragung zustimmen:\",\"info_link\":\"http:\\\/\\\/www.heise.de\\\/ct\\\/artikel\\\/2-Klicks-fuer-mehr-Datenschutz-1333879.html\",\"uri\":\"https:\\\/\\\/www.burks.de\\\/burksblog\\\/2012\\\/09\\\/05\\\/auf-posten-in-einsamer-nacht\",\"post_id\":15744,\"post_title_referrer_track\":\"Auf+Posten+in+einsamer+Nacht\",\"display_infobox\":\"on\"});}});\n\/* ]]> *\/<\/script><\/div>","protected":false},"excerpt":{"rendered":"<p>Beim Schockwellenreiter wurde ich auf das wunderbare Historisch-kritische Liederlexikon aufmerksam. F\u00fcr Blogger wie mich passt nat\u00fcrlich &#8222;Auf Posten in einsamer Nacht&#8222;. &#8222;Singgruppe Lorelei&#8220; aus St. Petersburg (woher auch sonst), gesucht und gefunden bei Youtube! Lalala tamtam! Ohrwurm!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15744","post","type-post","status-publish","format-standard","hentry","category-feuilleton"],"_links":{"self":[{"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/posts\/15744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/comments?post=15744"}],"version-history":[{"count":5,"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/posts\/15744\/revisions"}],"predecessor-version":[{"id":15749,"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/posts\/15744\/revisions\/15749"}],"wp:attachment":[{"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/media?parent=15744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/categories?post=15744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/tags?post=15744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}