{"id":13447,"date":"2012-03-05T16:04:48","date_gmt":"2012-03-05T15:04:48","guid":{"rendered":"http:\/\/www.burks.de\/burksblog\/?p=13447"},"modified":"2012-03-05T16:05:25","modified_gmt":"2012-03-05T15:05:25","slug":"megatherion","status":"publish","type":"post","link":"https:\/\/www.burks.de\/burksblog\/2012\/03\/05\/megatherion","title":{"rendered":"Megatherion"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/www.burks.de\/burksblog\/pix\/2012\/03\/050312_3.jpg\" alt=\"Megatherion\" border=\"0\" hspace=\"0\" vspace=\"0\" width=\"480\" \/><\/p>\n<p align=left>In der N\u00e4he von Buenos Aires haben Forscher 30.000 Jahre alte Fu\u00dfabdr\u00fccke von Riesenfaultieren gefunden. Das berichtet <a href=\"http:\/\/www.spiegel.de\/wissenschaft\/natur\/0,1518,819310,00.html\">Spiegel Online<\/a>, ohne die Quelle zu verlinken:<br \/>\n<i>Die Spuren seien 30.000 Jahre alt, schreiben die Forscher in einer Mitteilung der Stiftung f\u00fcr Naturgeschichte &#8222;<a href=\"http:\/\/www.fundacionazara.org.ar\/\">F\u00e9lix de Azara<\/a>&#8220; und der Universit\u00e4t Maim\u00f3nides in Buenos Aires. Es handle sich um Abdr\u00fccke der Art Megatherium.<\/i><\/p>\n<p>Warum sie nur Fu\u00dfspuren, aber keine Knochen gefunden haben, erfahren die wohlwollenden Leserinnen und geneigten Leser von burks.de: Das Skelett hat schon jemand wegger\u00e4umt.<\/p>\n<p><i>Morgenstern aber sah weder diesen noch jene; sein Auge hing starr an dem Skelette; seine Brust rang nach Atem; er streckte beide Arme aus; er wollte sprechen, rufen, brachte aber kein Wort hervor, bis er endlich mit Aufbietung aller seiner Kr\u00e4fte in gellendem Tone und silbenweise schrie: &#8222;Ein &#8211; Me &#8211; ga &#8211; the &#8211; ri &#8211; um! &#8211; Ein &#8211; Rie &#8211; sen &#8211; faul &#8211; tier!&#8220; (&#8230;) <\/p>\n<p>Leider soll der Name der deutschen Stadt nicht genannt werden, in welcher Doktor Morgenstern seinen Studien lebt. Er ist durch sein Megatherium ber\u00fchmt geworden und unternimmt mit seinem treuen Fritze zuweilen eine Reise in ferne Gegenden, um das Skelett eines Urmenschen zu entdecken. N\u00e4chstens wird er zu diesem Zwecke nach Sibirien gehen. Der Inka hat Tharandt besucht und ist J\u00e4ger geworden, in welchem Berufe ihn der nun uralte Anciano noch immer r\u00fcstig unterst\u00fctzt. Engelhardt lebt als Rentier am sch\u00f6nen gr\u00fcnen Rhein, wo Anton mit seinem Bruder eine bedeutende Weinhandlung gegr\u00fcndet hat.<\/i><\/p>\n<p>Liest du <a href=\"http:\/\/www.karl-may-gesellschaft.de\/kmg\/primlit\/jugend\/inka\/kptl_4.htm\">hier<\/a> und <a href=\"http:\/\/www.karl-may-gesellschaft.de\/kmg\/primlit\/jugend\/inka\/kptl_5.htm\">hier<\/a> nach.<\/p>\n<div class=\"pdfprnt-buttons pdfprnt-buttons-post pdfprnt-bottom-right\"><a href=\"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/posts\/13447?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/www.burks.de\/burksblog\/wp-content\/plugins\/pdf-print\/images\/pdf.png\" alt=\"image_pdf\" title=\"PDF anzeigen\" \/><\/a><a href=\"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/posts\/13447?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\" ><img decoding=\"async\" src=\"https:\/\/www.burks.de\/burksblog\/wp-content\/plugins\/pdf-print\/images\/print.png\" alt=\"image_print\" title=\"Inhalt drucken\" \/><\/a><\/div><div class=\"twoclick_social_bookmarks_post_13447 social_share_privacy clearfix 1.6.4 locale-de_DE sprite-de_DE\"><\/div><div class=\"twoclick-js\"><script type=\"text\/javascript\">\/* <![CDATA[ *\/\njQuery(document).ready(function($){if($('.twoclick_social_bookmarks_post_13447')){$('.twoclick_social_bookmarks_post_13447').socialSharePrivacy({\"services\":{\"facebook\":{\"status\":\"on\",\"txt_info\":\"2 Klicks f\\u00fcr mehr Datenschutz: Erst wenn Sie hier klicken, wird der Button aktiv und Sie k\\u00f6nnen Ihre Empfehlung an Facebook senden. Schon beim Aktivieren werden Daten an Dritte \\u00fcbertragen - siehe <em>i<\\\/em>.\",\"perma_option\":\"off\",\"action\":\"recommend\",\"language\":\"de_DE\"},\"twitter\":{\"reply_to\":\"\",\"tweet_text\":\"Megatherion%20%C2%BB%20Burks%27%20Blog%20-%20in%20dubio%20pro%20contra.%20De%20omnibus%20dubitandum.\",\"status\":\"on\",\"txt_info\":\"2 Klicks f\\u00fcr mehr Datenschutz: Erst wenn Sie hier klicken, wird der Button aktiv und Sie k\\u00f6nnen Ihre Empfehlung an Twitter senden. Schon beim Aktivieren werden Daten an Dritte \\u00fcbertragen - siehe <em>i<\\\/em>.\",\"perma_option\":\"off\",\"language\":\"de\",\"referrer_track\":\"\"}},\"txt_help\":\"Wenn Sie diese Felder durch einen Klick aktivieren, werden Informationen an Facebook, Twitter, Flattr, Xing, t3n, LinkedIn, Pinterest oder Google eventuell ins Ausland \\u00fcbertragen und unter Umst\\u00e4nden auch dort gespeichert. N\\u00e4heres erfahren Sie durch einen Klick auf das <em>i<\\\/em>.\",\"settings_perma\":\"Dauerhaft aktivieren und Daten\\u00fcber-tragung zustimmen:\",\"info_link\":\"http:\\\/\\\/www.heise.de\\\/ct\\\/artikel\\\/2-Klicks-fuer-mehr-Datenschutz-1333879.html\",\"uri\":\"https:\\\/\\\/www.burks.de\\\/burksblog\\\/2012\\\/03\\\/05\\\/megatherion\",\"post_id\":13447,\"post_title_referrer_track\":\"Megatherion\",\"display_infobox\":\"on\"});}});\n\/* ]]> *\/<\/script><\/div>","protected":false},"excerpt":{"rendered":"<p>In der N\u00e4he von Buenos Aires haben Forscher 30.000 Jahre alte Fu\u00dfabdr\u00fccke von Riesenfaultieren gefunden. Das berichtet Spiegel Online, ohne die Quelle zu verlinken: Die Spuren seien 30.000 Jahre alt, schreiben die Forscher in einer Mitteilung der Stiftung f\u00fcr Naturgeschichte &#8222;F\u00e9lix de Azara&#8220; und der Universit\u00e4t Maim\u00f3nides in Buenos Aires. Es handle sich um Abdr\u00fccke [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,17],"tags":[],"class_list":["post-13447","post","type-post","status-publish","format-standard","hentry","category-feuilleton","category-science"],"_links":{"self":[{"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/posts\/13447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/comments?post=13447"}],"version-history":[{"count":5,"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/posts\/13447\/revisions"}],"predecessor-version":[{"id":13452,"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/posts\/13447\/revisions\/13452"}],"wp:attachment":[{"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/media?parent=13447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/categories?post=13447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.burks.de\/burksblog\/wp-json\/wp\/v2\/tags?post=13447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}